{"id":156,"count":1,"description":"","link":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/tag\/iom3-awards\/","name":"IOM3 awards","slug":"iom3-awards","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IOM3 awards Archives - Department of Materials Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IOM3 awards Archives - Department of Materials Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/tag\/iom3-awards\/\" \/>\n<meta property=\"og:site_name\" content=\"Department of Materials Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/tag\\\/iom3-awards\\\/\",\"url\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/tag\\\/iom3-awards\\\/\",\"name\":\"IOM3 awards Archives - Department of Materials Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/tag\\\/iom3-awards\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/tag\\\/iom3-awards\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IOM3 awards\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/\",\"name\":\"Department of Materials Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/#organization\",\"name\":\"Department of Materials Blog\",\"url\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2018\\\/05\\\/university-of-manchester.png\",\"contentUrl\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2018\\\/05\\\/university-of-manchester.png\",\"width\":206,\"height\":86,\"caption\":\"Department of Materials Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/materials-blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IOM3 awards Archives - Department of Materials Blog","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"IOM3 awards Archives - Department of Materials Blog","og_url":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/tag\/iom3-awards\/","og_site_name":"Department of Materials Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/tag\/iom3-awards\/","url":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/tag\/iom3-awards\/","name":"IOM3 awards Archives - Department of Materials Blog","isPartOf":{"@id":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/tag\/iom3-awards\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/tag\/iom3-awards\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/"},{"@type":"ListItem","position":2,"name":"IOM3 awards"}]},{"@type":"WebSite","@id":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/#website","url":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/","name":"Department of Materials Blog","description":"","publisher":{"@id":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/#organization","name":"Department of Materials Blog","url":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/wp-content\/uploads\/sites\/12\/2018\/05\/university-of-manchester.png","contentUrl":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/wp-content\/uploads\/sites\/12\/2018\/05\/university-of-manchester.png","width":206,"height":86,"caption":"Department of Materials Blog"},"image":{"@id":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/wp-json\/wp\/v2\/tags\/156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sites.se.manchester.ac.uk\/materials-blog\/wp-json\/wp\/v2\/posts?tags=156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}