{"id":178,"count":1,"description":"","link":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/tag\/energy-projects\/","name":"energy projects","slug":"energy-projects","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>energy projects Archives - Department of Earth and Environmental Sciences Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"energy projects Archives - Department of Earth and Environmental Sciences Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/tag\/energy-projects\/\" \/>\n<meta property=\"og:site_name\" content=\"Department of Earth and Environmental Sciences Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/tag\\\/energy-projects\\\/\",\"url\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/tag\\\/energy-projects\\\/\",\"name\":\"energy projects Archives - Department of Earth and Environmental Sciences Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/tag\\\/energy-projects\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/tag\\\/energy-projects\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"energy projects\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/\",\"name\":\"Department of Earth and Environmental Sciences Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/#organization\",\"name\":\"Department of Earth and Environmental Sciences Blog\",\"url\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/05\\\/logo-university-of-manchester-1.png\",\"contentUrl\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/05\\\/logo-university-of-manchester-1.png\",\"width\":206,\"height\":86,\"caption\":\"Department of Earth and Environmental Sciences Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sites.se.manchester.ac.uk\\\/earth-sciences-blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"energy projects Archives - Department of Earth and Environmental Sciences Blog","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"energy projects Archives - Department of Earth and Environmental Sciences Blog","og_url":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/tag\/energy-projects\/","og_site_name":"Department of Earth and Environmental Sciences Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/tag\/energy-projects\/","url":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/tag\/energy-projects\/","name":"energy projects Archives - Department of Earth and Environmental Sciences Blog","isPartOf":{"@id":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/tag\/energy-projects\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/tag\/energy-projects\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/"},{"@type":"ListItem","position":2,"name":"energy projects"}]},{"@type":"WebSite","@id":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/#website","url":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/","name":"Department of Earth and Environmental Sciences Blog","description":"","publisher":{"@id":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/#organization","name":"Department of Earth and Environmental Sciences Blog","url":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/wp-content\/uploads\/sites\/9\/2019\/05\/logo-university-of-manchester-1.png","contentUrl":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/wp-content\/uploads\/sites\/9\/2019\/05\/logo-university-of-manchester-1.png","width":206,"height":86,"caption":"Department of Earth and Environmental Sciences Blog"},"image":{"@id":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/wp-json\/wp\/v2\/tags\/178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sites.se.manchester.ac.uk\/earth-sciences-blog\/wp-json\/wp\/v2\/posts?tags=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}